{"id":10961,"date":"2022-06-09T16:04:13","date_gmt":"2022-06-09T08:04:13","guid":{"rendered":"https:\/\/taizyfoodmachinery.com\/?p=10961"},"modified":"2024-09-18T14:15:40","modified_gmt":"2024-09-18T06:15:40","slug":"peanut-butter-production-line","status":"publish","type":"post","link":"https:\/\/taizyfoodmachinery.com\/de\/peanut-butter-production-line\/","title":{"rendered":"Erdnussbutter-Produktionslinie | Maschine zur Herstellung von Erdnussbutter"},"content":{"rendered":"<div class=\"kk-star-ratings kksr-auto kksr-align-left kksr-valign-top\"     data-payload='{&quot;align&quot;:&quot;left&quot;,&quot;id&quot;:&quot;10961&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;top&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;5&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;4.6&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;Rate this post&quot;,&quot;legend&quot;:&quot;4.6\\\/5 - (5 votes)&quot;,&quot;size&quot;:&quot;24&quot;,&quot;title&quot;:&quot;Peanut Butter Production Line | Peanut Butter Making Machine&quot;,&quot;width&quot;:&quot;130.9&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>              <div class=\"kksr-stars\">      <div class=\"kksr-stars-inactive\">             <div class=\"kksr-star\" data-star=\"1\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" data-star=\"2\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" data-star=\"3\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" data-star=\"4\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" data-star=\"5\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>     <\/div>      <div class=\"kksr-stars-active\" style=\"width: 130.9px;\">             <div class=\"kksr-star\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>             <div class=\"kksr-star\" style=\"padding-right: 5px\">               <div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>         <\/div>     <\/div> <\/div>                   <div class=\"kksr-legend\" style=\"font-size: 19.2px;\">             4.6\/5 - (5 votes)    <\/div>     <\/div>  <p>Die Erdnussbutter-Produktionslinie ist eine spezielle Verarbeitungslinie zur Herstellung von Erdnussbutter. Unser Unternehmen ist seit Jahren auf die Herstellung und den Handel hochwertiger Erdnussbutter-Produktionslinien spezialisiert, die universell in der kleinen industriellen und kommerziellen Erdnussbutterherstellung eingesetzt werden. Erdnussbutter wird durch R\u00f6sten, Sch\u00e4len und Mahlen hergestellt. Und es kann eine Produktion in gro\u00dfem Ma\u00dfstab realisieren. Dar\u00fcber hinaus kann die gesamte Produktionslinie als halbautomatische oder vollautomatische Produktionslinie ausgelegt werden. Es ist ein Tafelprodukt mit hohem N\u00e4hrwert.<\/p>    <figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"540\" height=\"540\" sizes=\"auto, (max-width: 540px) 100vw, 540px\" src=\"https:\/\/taizyfoodmachinery.com\/wp-content\/uploads\/2021\/10\/Peanut-butter-processing-line.jpg\" alt=\"Verarbeitung von Erdnussbutter \" class=\"wp-image-13134\"\/><figcaption class=\"wp-element-caption\">Verarbeitung von Erdnussbutter <\/figcaption><\/figure>    <h2 class=\"wp-block-heading\" id=\"h-the-processing-production-of-peanut-butter\">Die Verarbeitung von Erdnussbutter<\/h2>    <p class=\"translation-block\"><strong>R\u00f6sten:<\/strong> Die Erdn\u00fcsse m\u00fcssen zuerst ger\u00f6stet werden. Da die ger\u00f6steten Erdn\u00fcsse einen starken Duft haben. Daher m\u00fcssen Sie eine <a href=\"https:\/\/taizyfoodmachinery.com\/de\/peanut-roasting-machine-nut-roasting-equipment\/\">Erdnussr\u00f6ster<\/a> verwenden, um diese Funktion zu erf\u00fcllen. Dies kann den Geschmack der Erdnussbutter k\u00f6stlich machen. Danach m\u00fcssen die Erdn\u00fcsse nach dem R\u00f6sten abgek\u00fchlt werden, um mit dem n\u00e4chsten Schritt fortfahren zu k\u00f6nnen. Da die frisch ger\u00f6steten Erdn\u00fcsse zu hei\u00df sind. <\/p>    <p class=\"translation-block\"><strong>Sch\u00e4len: <\/strong>Wir alle wissen, dass Erdn\u00fcsse eine rote Haut haben. Wenn sie nicht behandelt werden, beeinflusst dies direkt den Geschmack der Erdnussbutter. Der Taizy-Erdnusssch\u00e4ler kann die ger\u00f6steten und abgek\u00fchlten Erdn\u00fcsse sch\u00e4len und halbieren. Dar\u00fcber hinaus werden einige der k\u00f6rnigen Keime auch ausgesiebt, um die Qualit\u00e4t der Erdnussbutter zu gew\u00e4hrleisten.<\/p>    <p class=\"translation-block\"><strong>Mahlen: <\/strong>Durch das Mahlen werden Erdn\u00fcsse wirklich zu Erdnussbutter. Die gesch\u00e4lten Erdn\u00fcsse werden von mehreren <a href=\"https:\/\/taizyfoodmachinery.com\/de\/colloid-mill-peanut-butter-machine\/\">Erdnussbutter-Kolloidm\u00fchlen<\/a> zu einer Paste gemahlen und treten dann nacheinander in den Mischbeh\u00e4lter und den Vakuumbeh\u00e4lter ein und k\u00f6nnen dann abgef\u00fcllt werden, um die ganze Flasche Erdnussbutter zu erhalten.<\/p>    <p class=\"translation-block\"><strong>Mischen<\/strong>: Um den Geschmack der Erdnussbutter einzigartiger zu machen, f\u00fcgen viele Erdnussbutterhersteller Salz, Zucker und andere Gew\u00fcrze hinzu. Dar\u00fcber hinaus ben\u00f6tigen wir Mischgl\u00e4ser, damit sie gleichm\u00e4\u00dfig vermischt werden k\u00f6nnen, um den Geschmack einheitlicher zu machen.<\/p>    <p class=\"translation-block\"><strong>Entgasen<\/strong>: Der Vakuum-Entgasungsbeh\u00e4lter kann das Gas effektiv aus der Erdnussbutter entfernen. Dies kann die Lagerzeit der Erdnussbutter effektiv verl\u00e4ngern.<\/p>    <p class=\"translation-block\"><strong>Verpackung<\/strong>: Schlie\u00dflich m\u00fcssen wir die Verpackungsmaschine verwenden, um die Erdnussbutter in Fertigprodukte zu verpacken und sie dann zu verkaufen.<\/p>    <p>Aus dem Herstellungsprozess von Erdnussbutter k\u00f6nnen wir wissen, dass die Produktionslinie f\u00fcr Erdnussbutter haupts\u00e4chlich R\u00f6sten, K\u00fchlen, Sch\u00e4len, Mahlen, Mischen, Entgasen und Verpacken umfasst. Zu den wichtigsten Schritten geh\u00f6ren das Backen, das Halbkornsch\u00e4len und das Mahlen.<\/p>    <figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"540\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" src=\"https:\/\/taizyfoodmachinery.com\/wp-content\/uploads\/2021\/10\/Peanut-butter-production.jpg\" alt=\"Produktionslinie f\u00fcr Erdnussbutter\" class=\"wp-image-10994\" srcset=\"https:\/\/taizyfoodmachinery.com\/wp-content\/uploads\/2021\/10\/Peanut-butter-production.jpg 1000w, https:\/\/taizyfoodmachinery.com\/wp-content\/uploads\/2021\/10\/Peanut-butter-production-768x415.jpg 768w\" \/><figcaption class=\"wp-element-caption\">Produktionslinie f\u00fcr Erdnussbutter<\/figcaption><\/figure>    <h2 class=\"wp-block-heading\">Parameter der 500 kg\/h Erdnussbutter-Produktionslinie<\/h2>    <figure class=\"wp-block-table\"><table><tbody><tr><td><strong>Produktionslinie f\u00fcr 500 kg Erdnussbutter<\/strong><\/td><td><strong>Abmessungen<\/strong><\/td><td><strong>Gewicht<\/strong><\/td><td><strong>Leistung<\/strong><\/td><td><strong>Kapazit\u00e4t (kg\/h)<\/strong><\/td><\/tr><tr><td>Maschine zum R\u00f6sten und K\u00fchlen von Erdn\u00fcssen<\/td><td>8500*1800*2600mm<\/td><td>2000kg<\/td><td>130 kW<\/td><td>500kg\/h<\/td><\/tr><tr><td>Erdnusssch\u00e4lmaschine<\/td><td>1900*800*1350mm<\/td><td>500kg<\/td><td>3 kW<\/td><td>500kg\/h<\/td><\/tr><tr><td>Kombinierte Kolloidm\u00fchle<\/td><td>1400*1250*2000mm<\/td><td>650kg<\/td><td>30x2kw<\/td><td>500kg\/h<\/td><\/tr><tr><td>Vakuum-, Misch- und Lagertank<\/td><td>1500*250*250mm<\/td><td>200kg<\/td><td>1,5 kW<\/td><td>50kg\/h*3<\/td><\/tr><tr><td>Abf\u00fcllmaschine<\/td><td>400*400*1400mm<\/td><td>1000kg<\/td><td>1,1 kW<\/td><td>100-400 Dosen\/h<\/td><\/tr><\/tbody><\/table><figcaption class=\"wp-element-caption\">Parameterliste<\/figcaption><\/figure>    <p class=\"translation-block\">Dies sind die Maschinenparameter der Erdnussbutter-Verarbeitungslinie. Mit dieser Verarbeitungslinie k\u00f6nnen Sie in einer Stunde 500 kg Erdnussbutter erhalten. Wenn Sie andere Ausgabeanforderungen haben, k\u00f6nnen Sie sich gerne <a href=\"https:\/\/taizyfoodmachinery.com\/de\/page\/1\/?s=peanut#text-3\">mit uns in Verbindung setzen<\/a>.<\/p>    <h2 class=\"wp-block-heading\">Kleine Produktionslinie f\u00fcr Erdnussbutter<\/h2>    <p>Wenn Ihr Budget begrenzt ist und Sie eine kleine Produktionslinie f\u00fcr Erdnussbutter w\u00fcnschen, k\u00f6nnen wir Ihnen ma\u00dfgeschneiderte Dienstleistungen anbieten.<\/p>    <ol class=\"wp-block-list\"> <li>Wir alle wissen, dass der Preis der Maschine zur Herstellung von Erdnussbutter umso h\u00f6her ist, je gr\u00f6\u00dfer die Produktion von Erdnussbutter ist. Wir k\u00f6nnen f\u00fcr Sie eine kleine Produktionslinie ausw\u00e4hlen, beispielsweise eine Erdnussbutter-Verarbeitungslinie mit 200 kg\/h.<\/li>    <li>Zweitens k\u00f6nnen Sie nur einen Erdnussr\u00f6ster, einen Erdnusssch\u00e4ler und eine Erdnussbutter-Mahlmaschine w\u00e4hlen. Mit nur diesen drei Maschinen k\u00f6nnen Sie auch ganz einfach Ihre Erdnussbutterproduktion starten.<\/li> <\/ol>    <figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" src=\"https:\/\/taizyfoodmachinery.com\/wp-content\/uploads\/2020\/11\/peanut-butter-making.jpg\" alt=\"Erdnussbutter\" class=\"wp-image-5315\" srcset=\"https:\/\/taizyfoodmachinery.com\/wp-content\/uploads\/2020\/11\/peanut-butter-making.jpg 720w, https:\/\/taizyfoodmachinery.com\/wp-content\/uploads\/2020\/11\/peanut-butter-making-300x225.jpg 300w, https:\/\/taizyfoodmachinery.com\/wp-content\/uploads\/2020\/11\/peanut-butter-making-414x310.jpg 414w, https:\/\/taizyfoodmachinery.com\/wp-content\/uploads\/2020\/11\/peanut-butter-making-74x55.jpg 74w, https:\/\/taizyfoodmachinery.com\/wp-content\/uploads\/2020\/11\/peanut-butter-making-111x83.jpg 111w\" \/><figcaption class=\"wp-element-caption\">Erdnussbutter<\/figcaption><\/figure>    <h2 class=\"wp-block-heading\" id=\"h-what-you-should-know-about-building-a-peanut-butter-processing-plant\">Was sollten Sie \u00fcber den Bau einer Erdnussbutter-Verarbeitungsanlage wissen?<\/h2>    <ol class=\"wp-block-list\"> <li>Bevor Sie investieren, m\u00fcssen Sie zun\u00e4chst Marktforschung betreiben. Bestimmen Sie die Marktposition anhand des Inputs und Outputs. Sie m\u00fcssen beispielsweise ber\u00fccksichtigen, wie viele Erdn\u00fcsse jedes Jahr vor Ort produziert werden.<\/li>    <li>Vertriebskan\u00e4le erschlie\u00dfen und Zielkunden identifizieren. F\u00fchren Sie eine angemessene Marktforschung durch, um eine gute Grundlage f\u00fcr die Gr\u00fcndung von Erdnussbutterfabriken zu schaffen.<\/li>    <li>Beginnen Sie mit dem Bau der Fabrik. Sie m\u00fcssen einen Anlagenplan nach den Grunds\u00e4tzen der Anlagenplanung erstellen. Und auf dieser Grundlage sollten Sie die Materialbuchhaltung, die Berechnung der Verbrauchsmaterialien, die Auswahl der Erdnussbuttermaschine sowie die Berechnung des Wasser-, Strom- und Dampfverbrauchs durchf\u00fchren.<\/li>    <li>Beim Bau einer Fabrik m\u00fcssen der Entwicklungsstand und der Entwicklungstrend von Erdnussbutter vollst\u00e4ndig ber\u00fccksichtigt werden. Dann entscheiden Sie sich unter dem Gesichtspunkt der Energieeinsparung f\u00fcr Erdnussbutter-Verarbeitungsger\u00e4te.<\/li> <\/ol>    <figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" src=\"https:\/\/taizyfoodmachinery.com\/wp-content\/uploads\/2021\/10\/Automatic-Peanut-Butter-Production-Line-1.jpg\" alt=\"Automatische Produktionslinie f\u00fcr Erdnussbutter\" class=\"wp-image-10986\" srcset=\"https:\/\/taizyfoodmachinery.com\/wp-content\/uploads\/2021\/10\/Automatic-Peanut-Butter-Production-Line-1.jpg 720w, https:\/\/taizyfoodmachinery.com\/wp-content\/uploads\/2021\/10\/Automatic-Peanut-Butter-Production-Line-1-300x225.jpg 300w, https:\/\/taizyfoodmachinery.com\/wp-content\/uploads\/2021\/10\/Automatic-Peanut-Butter-Production-Line-1-414x310.jpg 414w, https:\/\/taizyfoodmachinery.com\/wp-content\/uploads\/2021\/10\/Automatic-Peanut-Butter-Production-Line-1-74x55.jpg 74w, https:\/\/taizyfoodmachinery.com\/wp-content\/uploads\/2021\/10\/Automatic-Peanut-Butter-Production-Line-1-111x83.jpg 111w\" \/><figcaption class=\"wp-element-caption\">Automatische Produktionslinie f\u00fcr Erdnussbutter<\/figcaption><\/figure>    <h2 class=\"wp-block-heading\">Vorteile der Erdnussbutter<strong> <\/strong>Flie\u00dfband<\/h2>    <ol class=\"wp-block-list\"> <li>Entsprechend der Marktnachfrage wurde die Erdnussbutter verbessert und optimiert, so dass die Feinheit der Erdnussbutter weiter erh\u00f6ht wurde. <\/li>    <li>Es bietet den Vorteil einer einfachen Bedienung, eines stabilen Betriebs, eines geringeren Ger\u00e4uschpegels, einer einfachen Wartung, Korrosionsbest\u00e4ndigkeit, einer breiten Anwendung, einer guten Zuverl\u00e4ssigkeit usw.<\/li>    <li>Diese Produktionslinie ist auf den M\u00e4rkten verschiedener L\u00e4nder beliebt. <\/li>    <li>Dar\u00fcber hinaus eignet sich diese Erdnussbutter-Produktionslinie nicht nur f\u00fcr Erdn\u00fcsse, sondern auch f\u00fcr Sesamsamen, Raps und andere Materialien.<\/li> <\/ol>    <figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"540\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" src=\"https:\/\/taizyfoodmachinery.com\/wp-content\/uploads\/2022\/06\/high-quality-peanut-butter.jpg\" alt=\"hochwertige Erdnussbutter\" class=\"wp-image-15192\" srcset=\"https:\/\/taizyfoodmachinery.com\/wp-content\/uploads\/2022\/06\/high-quality-peanut-butter.jpg 720w, https:\/\/taizyfoodmachinery.com\/wp-content\/uploads\/2022\/06\/high-quality-peanut-butter-300x225.jpg 300w, https:\/\/taizyfoodmachinery.com\/wp-content\/uploads\/2022\/06\/high-quality-peanut-butter-150x113.jpg 150w, https:\/\/taizyfoodmachinery.com\/wp-content\/uploads\/2022\/06\/high-quality-peanut-butter-16x12.jpg 16w\" \/><figcaption class=\"wp-element-caption\">hochwertige Erdnussbutter<\/figcaption><\/figure>    <h2 class=\"wp-block-heading\">3D-Demonstrationsvideo des Erdnussbutter-Produktionsprozesses<\/h2>    <figure class=\"wp-block-embed is-type-rich is-provider-embed-handler wp-block-embed-embed-handler wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\"> <iframe loading=\"lazy\" title=\"3D-Demonstrationsvideo der Erdnussbutterproduktion\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/xMOjeA5LShY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe> <\/div><figcaption class=\"wp-element-caption\">Video des Erdnussbutter-Produktionsprozesses<\/figcaption><\/figure>    <p><\/p>","protected":false},"excerpt":{"rendered":"<p>Unser Unternehmen ist seit Jahren auf die Herstellung und den Handel hochwertiger Erdnussmaschinen spezialisiert, die universell in der kleinindustriellen und kommerziellen Erdnussbutterherstellung eingesetzt werden. Unsere Erdnussbutter-Produktionslinie verf\u00fcgt \u00fcber ein vern\u00fcnftiges Design, einen hohen Automatisierungsgrad, eine vollst\u00e4ndig geschlossene Produktion, keine Umweltverschmutzung und kann eine Produktion in gro\u00dfem Ma\u00dfstab realisieren. Die gesamte Produktionslinie kann als halbautomatische oder vollautomatische Produktionslinie ausgelegt sein, teilweise auch individuell nach Kundenwunsch. <\/p>","protected":false},"author":1,"featured_media":15190,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[1],"tags":[3738],"post_format":[],"class_list":["post-10961","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-products","tag-peanut"],"views":1,"taxonomy_info":{"category":[{"value":1,"label":"Products"}],"post_tag":[{"value":3738,"label":"peanut"}]},"featured_image_src_large":["https:\/\/taizyfoodmachinery.com\/wp-content\/uploads\/2022\/06\/complete-peanut-butter-production-line.jpg",750,750,false],"author_info":{"display_name":"Taizy Machinery","author_link":"https:\/\/taizyfoodmachinery.com\/de\/author\/tzfoodmachine\/"},"comment_info":"","category_info":[{"term_id":1,"name":"Products","slug":"products","term_group":0,"term_taxonomy_id":1,"taxonomy":"category","description":"","parent":0,"count":85,"filter":"raw","cat_ID":1,"category_count":85,"category_description":"","cat_name":"Products","category_nicename":"products","category_parent":0}],"tag_info":[{"term_id":3738,"name":"peanut","slug":"peanut","term_group":0,"term_taxonomy_id":3738,"taxonomy":"post_tag","description":"","parent":0,"count":11,"filter":"raw"}],"_links":{"self":[{"href":"https:\/\/taizyfoodmachinery.com\/de\/wp-json\/wp\/v2\/posts\/10961","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/taizyfoodmachinery.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/taizyfoodmachinery.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/taizyfoodmachinery.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/taizyfoodmachinery.com\/de\/wp-json\/wp\/v2\/comments?post=10961"}],"version-history":[{"count":0,"href":"https:\/\/taizyfoodmachinery.com\/de\/wp-json\/wp\/v2\/posts\/10961\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/taizyfoodmachinery.com\/de\/wp-json\/wp\/v2\/media\/15190"}],"wp:attachment":[{"href":"https:\/\/taizyfoodmachinery.com\/de\/wp-json\/wp\/v2\/media?parent=10961"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/taizyfoodmachinery.com\/de\/wp-json\/wp\/v2\/categories?post=10961"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/taizyfoodmachinery.com\/de\/wp-json\/wp\/v2\/tags?post=10961"},{"taxonomy":"post_format","embeddable":true,"href":"https:\/\/taizyfoodmachinery.com\/de\/wp-json\/wp\/v2\/post_format?post=10961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}